{"id":11079,"date":"2025-05-27T17:33:00","date_gmt":"2025-05-27T15:33:00","guid":{"rendered":"https:\/\/campingelcarespicosdeeuropa.com\/?p=11079"},"modified":"2025-05-29T20:52:07","modified_gmt":"2025-05-29T18:52:07","slug":"n4-circular-route-pn-pr-pn15-senda-del-mercadillo","status":"publish","type":"post","link":"https:\/\/campingelcarespicosdeeuropa.com\/en\/n4-circular-route-pn-pr-pn15-senda-del-mercadillo\/","title":{"rendered":"N4. CIRCULAR ROUTE PN PR-PN15 SENDA DEL MERCADILLO."},"content":{"rendered":"\n<p>Easy circular route following the PN PR-15. Starting from Santa Marina de Valde\u00f3n, you will walk along a path that takes you through forests, meadows, and mountains, reaching impressive panoramic viewpoints. In addition, it will lead you to discover dreamlike spots such as the Fuente del Rejo, Collado Peranieva, and Fuente Torones.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/campingelcarespicosdeeuropa.com\/wp-content\/uploads\/2024\/09\/Captura-de-pantalla-2024-09-15-a-las-15.45.09-1024x723.png\" alt=\"\" class=\"wp-image-9650\"\/><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"505\" src=\"https:\/\/campingelcarespicosdeeuropa.com\/wp-content\/uploads\/2024\/09\/Captura-de-pantalla-2024-09-24-a-las-12.57.48-1024x505.png\" alt=\"\" class=\"wp-image-9812\" srcset=\"https:\/\/campingelcarespicosdeeuropa.com\/wp-content\/uploads\/2024\/09\/Captura-de-pantalla-2024-09-24-a-las-12.57.48-1024x505.png 1024w, https:\/\/campingelcarespicosdeeuropa.com\/wp-content\/uploads\/2024\/09\/Captura-de-pantalla-2024-09-24-a-las-12.57.48-300x148.png 300w, https:\/\/campingelcarespicosdeeuropa.com\/wp-content\/uploads\/2024\/09\/Captura-de-pantalla-2024-09-24-a-las-12.57.48-768x379.png 768w, https:\/\/campingelcarespicosdeeuropa.com\/wp-content\/uploads\/2024\/09\/Captura-de-pantalla-2024-09-24-a-las-12.57.48.png 1486w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Circular route from Camping El Cares passing through:<br>\u2022 Fuente del Rejo (0.5 km)<br>\u2022 Santa Marina de Valde\u00f3n (0.8 km)<br>\u2022 Collado Peranieva (3.0 km)<br>\u2022 Fuente Torones (3.8 km)<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><br>Route details<br><\/h2>\n\n\n\n<p>Distance: 11.79 km<br>Elevation gain: 676 m<br>Elevation loss: 676 m<br>Maximum altitude: 1,587 m<br>Minimum altitude: 959 m<br>Route type: Circular<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"735\" src=\"https:\/\/campingelcarespicosdeeuropa.com\/wp-content\/uploads\/2024\/09\/Captura-de-pantalla-2024-09-23-a-las-12.05.45-1024x735.png\" alt=\"\" class=\"wp-image-9753\" srcset=\"https:\/\/campingelcarespicosdeeuropa.com\/wp-content\/uploads\/2024\/09\/Captura-de-pantalla-2024-09-23-a-las-12.05.45-1024x735.png 1024w, https:\/\/campingelcarespicosdeeuropa.com\/wp-content\/uploads\/2024\/09\/Captura-de-pantalla-2024-09-23-a-las-12.05.45-300x215.png 300w, https:\/\/campingelcarespicosdeeuropa.com\/wp-content\/uploads\/2024\/09\/Captura-de-pantalla-2024-09-23-a-las-12.05.45-768x551.png 768w, https:\/\/campingelcarespicosdeeuropa.com\/wp-content\/uploads\/2024\/09\/Captura-de-pantalla-2024-09-23-a-las-12.05.45-1536x1102.png 1536w, https:\/\/campingelcarespicosdeeuropa.com\/wp-content\/uploads\/2024\/09\/Captura-de-pantalla-2024-09-23-a-las-12.05.45.png 1603w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p>Discover <a href=\"https:\/\/campingelcarespicosdeeuropa.com\/en\/category\/routes\/\">other<span style=\"box-sizing: border-box; margin: 0px; padding: 0px;\">\u00a0<\/span>hikes in the Valde\u00f3n Valley,<\/a> the heart of Picos de Europa.<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" width=\"24\" height=\"24\" src=\"https:\/\/campingelcarespicosdeeuropa.com\/wp-content\/uploads\/2024\/09\/pngwing.com_-300x300.png\" alt=\"\">&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; Follow the route <a href=\"https:\/\/es.wikiloc.com\/rutas-senderismo\/santa-marina-de-valdeon-collado-peranieva-y-fuente-torones-desde-santa-marina-de-valdeon-184466941\">Senda del Mercadillo<\/a><\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" width=\"65\" height=\"22\" src=\"https:\/\/campingelcarespicosdeeuropa.com\/wp-content\/uploads\/2024\/09\/retina-1593443677.jpg\" alt=\"\">  Follow the route <a href=\"https:\/\/www.komoot.com\/es-es\/tour\/1309430530?share_token=aNQTjAsIs0p5bT3dZypwMtklFsXUtGRQock6kO60EqqoyfrSFT&amp;ref=wtd\">Senda del mercadillo<\/a><\/p>\n\n\n\n<p><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/campingelcarespicosdeeuropa.com\/wp-content\/uploads\/2024\/09\/10900020-1024x1024.png\" alt=\"\" class=\"wp-image-9620\" style=\"width:58px;height:auto\" srcset=\"https:\/\/campingelcarespicosdeeuropa.com\/wp-content\/uploads\/2024\/09\/10900020-1024x1024.png 1024w, https:\/\/campingelcarespicosdeeuropa.com\/wp-content\/uploads\/2024\/09\/10900020-300x300.png 300w, https:\/\/campingelcarespicosdeeuropa.com\/wp-content\/uploads\/2024\/09\/10900020-150x150.png 150w, https:\/\/campingelcarespicosdeeuropa.com\/wp-content\/uploads\/2024\/09\/10900020-768x768.png 768w, https:\/\/campingelcarespicosdeeuropa.com\/wp-content\/uploads\/2024\/09\/10900020-1536x1536.png 1536w, https:\/\/campingelcarespicosdeeuropa.com\/wp-content\/uploads\/2024\/09\/10900020-600x600.png 600w, https:\/\/campingelcarespicosdeeuropa.com\/wp-content\/uploads\/2024\/09\/10900020.png 2000w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p>SEE VIDEO <img loading=\"lazy\" decoding=\"async\" width=\"64\" height=\"64\" src=\"https:\/\/campingelcarespicosdeeuropa.com\/wp-content\/uploads\/2024\/09\/icons8-youtube-64.png\" alt=\"\">&nbsp; &nbsp; SEE VIDEO<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Easy circular route following the PN PR-15. Starting from Santa Marina de Valde\u00f3n, you will walk along a path that takes you through forests, meadows, and mountains, reaching impressive panoramic viewpoints. In addition, it will lead you to discover dreamlike spots such as the Fuente del Rejo, Collado Peranieva, and Fuente Torones. Circular route from [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[162],"tags":[],"class_list":["post-11079","post","type-post","status-publish","format-standard","hentry","category-routes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>N4. CIRCULAR ROUTE PN PR-PN15 SENDA DEL MERCADILLO. - Camping El Cares<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/campingelcarespicosdeeuropa.com\/en\/n4-circular-route-pn-pr-pn15-senda-del-mercadillo\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"N4. CIRCULAR ROUTE PN PR-PN15 SENDA DEL MERCADILLO. - Camping El Cares\" \/>\n<meta property=\"og:description\" content=\"Easy circular route following the PN PR-15. Starting from Santa Marina de Valde\u00f3n, you will walk along a path that takes you through forests, meadows, and mountains, reaching impressive panoramic viewpoints. In addition, it will lead you to discover dreamlike spots such as the Fuente del Rejo, Collado Peranieva, and Fuente Torones. Circular route from [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/campingelcarespicosdeeuropa.com\/en\/n4-circular-route-pn-pr-pn15-senda-del-mercadillo\/\" \/>\n<meta property=\"og:site_name\" content=\"Camping El Cares\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-27T15:33:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-29T18:52:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/campingelcarespicosdeeuropa.com\/wp-content\/uploads\/2024\/09\/Captura-de-pantalla-2024-09-15-a-las-15.45.09-e1727892266352-1024x487.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"487\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Camping ElCares\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Camping ElCares\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/campingelcarespicosdeeuropa.com\\\/en\\\/n4-circular-route-pn-pr-pn15-senda-del-mercadillo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/campingelcarespicosdeeuropa.com\\\/en\\\/n4-circular-route-pn-pr-pn15-senda-del-mercadillo\\\/\"},\"author\":{\"name\":\"Camping ElCares\",\"@id\":\"https:\\\/\\\/campingelcarespicosdeeuropa.com\\\/en\\\/#\\\/schema\\\/person\\\/294070f0fde2fc95ae03b88bdda0df5e\"},\"headline\":\"N4. CIRCULAR ROUTE PN PR-PN15 SENDA DEL MERCADILLO.\",\"datePublished\":\"2025-05-27T15:33:00+00:00\",\"dateModified\":\"2025-05-29T18:52:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/campingelcarespicosdeeuropa.com\\\/en\\\/n4-circular-route-pn-pr-pn15-senda-del-mercadillo\\\/\"},\"wordCount\":137,\"publisher\":{\"@id\":\"https:\\\/\\\/campingelcarespicosdeeuropa.com\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/campingelcarespicosdeeuropa.com\\\/en\\\/n4-circular-route-pn-pr-pn15-senda-del-mercadillo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/campingelcarespicosdeeuropa.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Captura-de-pantalla-2024-09-15-a-las-15.45.09-1024x723.png\",\"articleSection\":[\"Routes\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/campingelcarespicosdeeuropa.com\\\/en\\\/n4-circular-route-pn-pr-pn15-senda-del-mercadillo\\\/\",\"url\":\"https:\\\/\\\/campingelcarespicosdeeuropa.com\\\/en\\\/n4-circular-route-pn-pr-pn15-senda-del-mercadillo\\\/\",\"name\":\"N4. CIRCULAR ROUTE PN PR-PN15 SENDA DEL MERCADILLO. - Camping El Cares\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/campingelcarespicosdeeuropa.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/campingelcarespicosdeeuropa.com\\\/en\\\/n4-circular-route-pn-pr-pn15-senda-del-mercadillo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/campingelcarespicosdeeuropa.com\\\/en\\\/n4-circular-route-pn-pr-pn15-senda-del-mercadillo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/campingelcarespicosdeeuropa.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Captura-de-pantalla-2024-09-15-a-las-15.45.09-1024x723.png\",\"datePublished\":\"2025-05-27T15:33:00+00:00\",\"dateModified\":\"2025-05-29T18:52:07+00:00\",\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/campingelcarespicosdeeuropa.com\\\/en\\\/n4-circular-route-pn-pr-pn15-senda-del-mercadillo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/campingelcarespicosdeeuropa.com\\\/en\\\/n4-circular-route-pn-pr-pn15-senda-del-mercadillo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/campingelcarespicosdeeuropa.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Captura-de-pantalla-2024-09-15-a-las-15.45.09-1024x723.png\",\"contentUrl\":\"https:\\\/\\\/campingelcarespicosdeeuropa.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Captura-de-pantalla-2024-09-15-a-las-15.45.09-1024x723.png\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/campingelcarespicosdeeuropa.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/campingelcarespicosdeeuropa.com\\\/en\\\/\",\"name\":\"Camping El Cares\",\"description\":\"Picos de Europa\",\"publisher\":{\"@id\":\"https:\\\/\\\/campingelcarespicosdeeuropa.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/campingelcarespicosdeeuropa.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/campingelcarespicosdeeuropa.com\\\/en\\\/#organization\",\"name\":\"Camping El Cares\",\"url\":\"https:\\\/\\\/campingelcarespicosdeeuropa.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/campingelcarespicosdeeuropa.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/campingelcarespicosdeeuropa.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/logo-camping-4-1.png\",\"contentUrl\":\"https:\\\/\\\/campingelcarespicosdeeuropa.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/logo-camping-4-1.png\",\"width\":762,\"height\":668,\"caption\":\"Camping El Cares\"},\"image\":{\"@id\":\"https:\\\/\\\/campingelcarespicosdeeuropa.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/campingelcarespicosdeeuropa.com\\\/en\\\/#\\\/schema\\\/person\\\/294070f0fde2fc95ae03b88bdda0df5e\",\"name\":\"Camping ElCares\",\"sameAs\":[\"http:\\\/\\\/campingelcarespicosdeeuropa.com\"],\"url\":\"https:\\\/\\\/campingelcarespicosdeeuropa.com\\\/en\\\/author\\\/admin6525\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"N4. CIRCULAR ROUTE PN PR-PN15 SENDA DEL MERCADILLO. - Camping El Cares","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/campingelcarespicosdeeuropa.com\/en\/n4-circular-route-pn-pr-pn15-senda-del-mercadillo\/","og_locale":"en_GB","og_type":"article","og_title":"N4. CIRCULAR ROUTE PN PR-PN15 SENDA DEL MERCADILLO. - Camping El Cares","og_description":"Easy circular route following the PN PR-15. Starting from Santa Marina de Valde\u00f3n, you will walk along a path that takes you through forests, meadows, and mountains, reaching impressive panoramic viewpoints. In addition, it will lead you to discover dreamlike spots such as the Fuente del Rejo, Collado Peranieva, and Fuente Torones. Circular route from [&hellip;]","og_url":"https:\/\/campingelcarespicosdeeuropa.com\/en\/n4-circular-route-pn-pr-pn15-senda-del-mercadillo\/","og_site_name":"Camping El Cares","article_published_time":"2025-05-27T15:33:00+00:00","article_modified_time":"2025-05-29T18:52:07+00:00","og_image":[{"width":1024,"height":487,"url":"https:\/\/campingelcarespicosdeeuropa.com\/wp-content\/uploads\/2024\/09\/Captura-de-pantalla-2024-09-15-a-las-15.45.09-e1727892266352-1024x487.png","type":"image\/png"}],"author":"Camping ElCares","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Camping ElCares","Estimated reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/campingelcarespicosdeeuropa.com\/en\/n4-circular-route-pn-pr-pn15-senda-del-mercadillo\/#article","isPartOf":{"@id":"https:\/\/campingelcarespicosdeeuropa.com\/en\/n4-circular-route-pn-pr-pn15-senda-del-mercadillo\/"},"author":{"name":"Camping ElCares","@id":"https:\/\/campingelcarespicosdeeuropa.com\/en\/#\/schema\/person\/294070f0fde2fc95ae03b88bdda0df5e"},"headline":"N4. CIRCULAR ROUTE PN PR-PN15 SENDA DEL MERCADILLO.","datePublished":"2025-05-27T15:33:00+00:00","dateModified":"2025-05-29T18:52:07+00:00","mainEntityOfPage":{"@id":"https:\/\/campingelcarespicosdeeuropa.com\/en\/n4-circular-route-pn-pr-pn15-senda-del-mercadillo\/"},"wordCount":137,"publisher":{"@id":"https:\/\/campingelcarespicosdeeuropa.com\/en\/#organization"},"image":{"@id":"https:\/\/campingelcarespicosdeeuropa.com\/en\/n4-circular-route-pn-pr-pn15-senda-del-mercadillo\/#primaryimage"},"thumbnailUrl":"https:\/\/campingelcarespicosdeeuropa.com\/wp-content\/uploads\/2024\/09\/Captura-de-pantalla-2024-09-15-a-las-15.45.09-1024x723.png","articleSection":["Routes"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/campingelcarespicosdeeuropa.com\/en\/n4-circular-route-pn-pr-pn15-senda-del-mercadillo\/","url":"https:\/\/campingelcarespicosdeeuropa.com\/en\/n4-circular-route-pn-pr-pn15-senda-del-mercadillo\/","name":"N4. CIRCULAR ROUTE PN PR-PN15 SENDA DEL MERCADILLO. - Camping El Cares","isPartOf":{"@id":"https:\/\/campingelcarespicosdeeuropa.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/campingelcarespicosdeeuropa.com\/en\/n4-circular-route-pn-pr-pn15-senda-del-mercadillo\/#primaryimage"},"image":{"@id":"https:\/\/campingelcarespicosdeeuropa.com\/en\/n4-circular-route-pn-pr-pn15-senda-del-mercadillo\/#primaryimage"},"thumbnailUrl":"https:\/\/campingelcarespicosdeeuropa.com\/wp-content\/uploads\/2024\/09\/Captura-de-pantalla-2024-09-15-a-las-15.45.09-1024x723.png","datePublished":"2025-05-27T15:33:00+00:00","dateModified":"2025-05-29T18:52:07+00:00","inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/campingelcarespicosdeeuropa.com\/en\/n4-circular-route-pn-pr-pn15-senda-del-mercadillo\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/campingelcarespicosdeeuropa.com\/en\/n4-circular-route-pn-pr-pn15-senda-del-mercadillo\/#primaryimage","url":"https:\/\/campingelcarespicosdeeuropa.com\/wp-content\/uploads\/2024\/09\/Captura-de-pantalla-2024-09-15-a-las-15.45.09-1024x723.png","contentUrl":"https:\/\/campingelcarespicosdeeuropa.com\/wp-content\/uploads\/2024\/09\/Captura-de-pantalla-2024-09-15-a-las-15.45.09-1024x723.png"},{"@type":"WebSite","@id":"https:\/\/campingelcarespicosdeeuropa.com\/en\/#website","url":"https:\/\/campingelcarespicosdeeuropa.com\/en\/","name":"Camping El Cares","description":"Picos de Europa","publisher":{"@id":"https:\/\/campingelcarespicosdeeuropa.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/campingelcarespicosdeeuropa.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/campingelcarespicosdeeuropa.com\/en\/#organization","name":"Camping El Cares","url":"https:\/\/campingelcarespicosdeeuropa.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/campingelcarespicosdeeuropa.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/campingelcarespicosdeeuropa.com\/wp-content\/uploads\/2024\/05\/logo-camping-4-1.png","contentUrl":"https:\/\/campingelcarespicosdeeuropa.com\/wp-content\/uploads\/2024\/05\/logo-camping-4-1.png","width":762,"height":668,"caption":"Camping El Cares"},"image":{"@id":"https:\/\/campingelcarespicosdeeuropa.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/campingelcarespicosdeeuropa.com\/en\/#\/schema\/person\/294070f0fde2fc95ae03b88bdda0df5e","name":"Camping ElCares","sameAs":["http:\/\/campingelcarespicosdeeuropa.com"],"url":"https:\/\/campingelcarespicosdeeuropa.com\/en\/author\/admin6525\/"}]}},"_links":{"self":[{"href":"https:\/\/campingelcarespicosdeeuropa.com\/en\/wp-json\/wp\/v2\/posts\/11079","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/campingelcarespicosdeeuropa.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/campingelcarespicosdeeuropa.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/campingelcarespicosdeeuropa.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/campingelcarespicosdeeuropa.com\/en\/wp-json\/wp\/v2\/comments?post=11079"}],"version-history":[{"count":5,"href":"https:\/\/campingelcarespicosdeeuropa.com\/en\/wp-json\/wp\/v2\/posts\/11079\/revisions"}],"predecessor-version":[{"id":11189,"href":"https:\/\/campingelcarespicosdeeuropa.com\/en\/wp-json\/wp\/v2\/posts\/11079\/revisions\/11189"}],"wp:attachment":[{"href":"https:\/\/campingelcarespicosdeeuropa.com\/en\/wp-json\/wp\/v2\/media?parent=11079"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/campingelcarespicosdeeuropa.com\/en\/wp-json\/wp\/v2\/categories?post=11079"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/campingelcarespicosdeeuropa.com\/en\/wp-json\/wp\/v2\/tags?post=11079"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}