{"id":9324,"date":"2024-03-09T06:58:19","date_gmt":"2024-03-09T05:58:19","guid":{"rendered":"https:\/\/campingelcarespicosdeeuropa.com\/tour\/via-ferrata\/"},"modified":"2025-03-29T10:30:04","modified_gmt":"2025-03-29T09:30:04","slug":"via-ferrata","status":"publish","type":"tour","link":"https:\/\/campingelcarespicosdeeuropa.com\/en\/tour\/via-ferrata\/","title":{"rendered":"V\u00eda Ferrata"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":10326,"template":"","meta":{"footnotes":""},"tour_category":[151],"tour_tag":[],"tour-age":[],"tour-activity":[145],"tour-destination":[],"class_list":["post-9324","tour","type-tour","status-publish","has-post-thumbnail","hentry","tour_category-via-ferrata-en","tour-activity-services"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>V\u00eda Ferrata - Camping El Cares<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/campingelcarespicosdeeuropa.com\/en\/tour\/via-ferrata\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"V\u00eda Ferrata - Camping El Cares\" \/>\n<meta property=\"og:url\" content=\"https:\/\/campingelcarespicosdeeuropa.com\/en\/tour\/via-ferrata\/\" \/>\n<meta property=\"og:site_name\" content=\"Camping El Cares\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-29T09:30:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/campingelcarespicosdeeuropa.com\/wp-content\/uploads\/2024\/03\/IMG_7580-scaled-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/campingelcarespicosdeeuropa.com\\\/en\\\/tour\\\/via-ferrata\\\/\",\"url\":\"https:\\\/\\\/campingelcarespicosdeeuropa.com\\\/en\\\/tour\\\/via-ferrata\\\/\",\"name\":\"V\u00eda Ferrata - Camping El Cares\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/campingelcarespicosdeeuropa.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/campingelcarespicosdeeuropa.com\\\/en\\\/tour\\\/via-ferrata\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/campingelcarespicosdeeuropa.com\\\/en\\\/tour\\\/via-ferrata\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/campingelcarespicosdeeuropa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/IMG_7580-scaled-1.webp\",\"datePublished\":\"2024-03-09T05:58:19+00:00\",\"dateModified\":\"2025-03-29T09:30:04+00:00\",\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/campingelcarespicosdeeuropa.com\\\/en\\\/tour\\\/via-ferrata\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/campingelcarespicosdeeuropa.com\\\/en\\\/tour\\\/via-ferrata\\\/#primaryimage\",\"url\":\"https:\\\/\\\/campingelcarespicosdeeuropa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/IMG_7580-scaled-1.webp\",\"contentUrl\":\"https:\\\/\\\/campingelcarespicosdeeuropa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/IMG_7580-scaled-1.webp\",\"width\":800,\"height\":600},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/campingelcarespicosdeeuropa.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/campingelcarespicosdeeuropa.com\\\/en\\\/\",\"name\":\"Camping El Cares\",\"description\":\"Picos de Europa\",\"publisher\":{\"@id\":\"https:\\\/\\\/campingelcarespicosdeeuropa.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/campingelcarespicosdeeuropa.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/campingelcarespicosdeeuropa.com\\\/en\\\/#organization\",\"name\":\"Camping El Cares\",\"url\":\"https:\\\/\\\/campingelcarespicosdeeuropa.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/campingelcarespicosdeeuropa.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/campingelcarespicosdeeuropa.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/logo-camping-4-1.png\",\"contentUrl\":\"https:\\\/\\\/campingelcarespicosdeeuropa.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/logo-camping-4-1.png\",\"width\":762,\"height\":668,\"caption\":\"Camping El Cares\"},\"image\":{\"@id\":\"https:\\\/\\\/campingelcarespicosdeeuropa.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"V\u00eda Ferrata - Camping El Cares","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/campingelcarespicosdeeuropa.com\/en\/tour\/via-ferrata\/","og_locale":"en_GB","og_type":"article","og_title":"V\u00eda Ferrata - Camping El Cares","og_url":"https:\/\/campingelcarespicosdeeuropa.com\/en\/tour\/via-ferrata\/","og_site_name":"Camping El Cares","article_modified_time":"2025-03-29T09:30:04+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/campingelcarespicosdeeuropa.com\/wp-content\/uploads\/2024\/03\/IMG_7580-scaled-1.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/campingelcarespicosdeeuropa.com\/en\/tour\/via-ferrata\/","url":"https:\/\/campingelcarespicosdeeuropa.com\/en\/tour\/via-ferrata\/","name":"V\u00eda Ferrata - Camping El Cares","isPartOf":{"@id":"https:\/\/campingelcarespicosdeeuropa.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/campingelcarespicosdeeuropa.com\/en\/tour\/via-ferrata\/#primaryimage"},"image":{"@id":"https:\/\/campingelcarespicosdeeuropa.com\/en\/tour\/via-ferrata\/#primaryimage"},"thumbnailUrl":"https:\/\/campingelcarespicosdeeuropa.com\/wp-content\/uploads\/2024\/03\/IMG_7580-scaled-1.webp","datePublished":"2024-03-09T05:58:19+00:00","dateModified":"2025-03-29T09:30:04+00:00","inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/campingelcarespicosdeeuropa.com\/en\/tour\/via-ferrata\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/campingelcarespicosdeeuropa.com\/en\/tour\/via-ferrata\/#primaryimage","url":"https:\/\/campingelcarespicosdeeuropa.com\/wp-content\/uploads\/2024\/03\/IMG_7580-scaled-1.webp","contentUrl":"https:\/\/campingelcarespicosdeeuropa.com\/wp-content\/uploads\/2024\/03\/IMG_7580-scaled-1.webp","width":800,"height":600},{"@type":"WebSite","@id":"https:\/\/campingelcarespicosdeeuropa.com\/en\/#website","url":"https:\/\/campingelcarespicosdeeuropa.com\/en\/","name":"Camping El Cares","description":"Picos de Europa","publisher":{"@id":"https:\/\/campingelcarespicosdeeuropa.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/campingelcarespicosdeeuropa.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/campingelcarespicosdeeuropa.com\/en\/#organization","name":"Camping El Cares","url":"https:\/\/campingelcarespicosdeeuropa.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/campingelcarespicosdeeuropa.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/campingelcarespicosdeeuropa.com\/wp-content\/uploads\/2024\/05\/logo-camping-4-1.png","contentUrl":"https:\/\/campingelcarespicosdeeuropa.com\/wp-content\/uploads\/2024\/05\/logo-camping-4-1.png","width":762,"height":668,"caption":"Camping El Cares"},"image":{"@id":"https:\/\/campingelcarespicosdeeuropa.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/campingelcarespicosdeeuropa.com\/en\/wp-json\/wp\/v2\/tour\/9324","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/campingelcarespicosdeeuropa.com\/en\/wp-json\/wp\/v2\/tour"}],"about":[{"href":"https:\/\/campingelcarespicosdeeuropa.com\/en\/wp-json\/wp\/v2\/types\/tour"}],"author":[{"embeddable":true,"href":"https:\/\/campingelcarespicosdeeuropa.com\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":5,"href":"https:\/\/campingelcarespicosdeeuropa.com\/en\/wp-json\/wp\/v2\/tour\/9324\/revisions"}],"predecessor-version":[{"id":10582,"href":"https:\/\/campingelcarespicosdeeuropa.com\/en\/wp-json\/wp\/v2\/tour\/9324\/revisions\/10582"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/campingelcarespicosdeeuropa.com\/en\/wp-json\/wp\/v2\/media\/10326"}],"wp:attachment":[{"href":"https:\/\/campingelcarespicosdeeuropa.com\/en\/wp-json\/wp\/v2\/media?parent=9324"}],"wp:term":[{"taxonomy":"tour_category","embeddable":true,"href":"https:\/\/campingelcarespicosdeeuropa.com\/en\/wp-json\/wp\/v2\/tour_category?post=9324"},{"taxonomy":"tour_tag","embeddable":true,"href":"https:\/\/campingelcarespicosdeeuropa.com\/en\/wp-json\/wp\/v2\/tour_tag?post=9324"},{"taxonomy":"tour-age","embeddable":true,"href":"https:\/\/campingelcarespicosdeeuropa.com\/en\/wp-json\/wp\/v2\/tour-age?post=9324"},{"taxonomy":"tour-activity","embeddable":true,"href":"https:\/\/campingelcarespicosdeeuropa.com\/en\/wp-json\/wp\/v2\/tour-activity?post=9324"},{"taxonomy":"tour-destination","embeddable":true,"href":"https:\/\/campingelcarespicosdeeuropa.com\/en\/wp-json\/wp\/v2\/tour-destination?post=9324"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}